{"id":138,"count":10,"description":"","link":"https:\/\/decolightingitaly.com\/de\/categoria-producto\/innenraum\/strahler\/","name":"Strahler","slug":"strahler","taxonomy":"product_cat","parent":105,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Strahler - Decolighting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/decolightingitaly.com\/de\/categoria-producto\/innenraum\/strahler\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Strahler - Decolighting\" \/>\n<meta property=\"og:url\" content=\"https:\/\/decolightingitaly.com\/de\/categoria-producto\/innenraum\/strahler\/\" \/>\n<meta property=\"og:site_name\" content=\"Decolighting\" \/>\n<meta property=\"og:image\" content=\"https:\/\/decolightingitaly.com\/wp-content\/uploads\/2024\/10\/Logo-v_3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"852\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/decolightingitaly.com\/de\/categoria-producto\/innenraum\/strahler\/\",\"url\":\"https:\/\/decolightingitaly.com\/de\/categoria-producto\/innenraum\/strahler\/\",\"name\":\"Strahler - Decolighting\",\"isPartOf\":{\"@id\":\"https:\/\/decolightingitaly.com\/de\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/decolightingitaly.com\/de\/categoria-producto\/innenraum\/strahler\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/decolightingitaly.com\/de\/categoria-producto\/innenraum\/strahler\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/decolightingitaly.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Strahler\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/decolightingitaly.com\/de\/#website\",\"url\":\"https:\/\/decolightingitaly.com\/de\/\",\"name\":\"Decolightingitaly\",\"description\":\"Illuminazione decorativa e di design\",\"publisher\":{\"@id\":\"https:\/\/decolightingitaly.com\/de\/#organization\"},\"alternateName\":\"Decolighting\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/decolightingitaly.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/decolightingitaly.com\/de\/#organization\",\"name\":\"Decolightingitaly\",\"alternateName\":\"Decolighting\",\"url\":\"https:\/\/decolightingitaly.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/decolightingitaly.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/decolightingitaly.com\/wp-content\/uploads\/2024\/10\/Logo-v_3.png\",\"contentUrl\":\"https:\/\/decolightingitaly.com\/wp-content\/uploads\/2024\/10\/Logo-v_3.png\",\"width\":852,\"height\":684,\"caption\":\"Decolightingitaly\"},\"image\":{\"@id\":\"https:\/\/decolightingitaly.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/people\/Decolighting-Italy\/61570211287982\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Strahler - Decolighting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/decolightingitaly.com\/de\/categoria-producto\/innenraum\/strahler\/","og_locale":"de_DE","og_type":"article","og_title":"Strahler - Decolighting","og_url":"https:\/\/decolightingitaly.com\/de\/categoria-producto\/innenraum\/strahler\/","og_site_name":"Decolighting","og_image":[{"width":852,"height":684,"url":"https:\/\/decolightingitaly.com\/wp-content\/uploads\/2024\/10\/Logo-v_3.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/decolightingitaly.com\/de\/categoria-producto\/innenraum\/strahler\/","url":"https:\/\/decolightingitaly.com\/de\/categoria-producto\/innenraum\/strahler\/","name":"Strahler - Decolighting","isPartOf":{"@id":"https:\/\/decolightingitaly.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/decolightingitaly.com\/de\/categoria-producto\/innenraum\/strahler\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/decolightingitaly.com\/de\/categoria-producto\/innenraum\/strahler\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/decolightingitaly.com\/de\/"},{"@type":"ListItem","position":2,"name":"Strahler"}]},{"@type":"WebSite","@id":"https:\/\/decolightingitaly.com\/de\/#website","url":"https:\/\/decolightingitaly.com\/de\/","name":"Decolightingitaly","description":"Illuminazione decorativa e di design","publisher":{"@id":"https:\/\/decolightingitaly.com\/de\/#organization"},"alternateName":"Decolighting","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/decolightingitaly.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/decolightingitaly.com\/de\/#organization","name":"Decolightingitaly","alternateName":"Decolighting","url":"https:\/\/decolightingitaly.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/decolightingitaly.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/decolightingitaly.com\/wp-content\/uploads\/2024\/10\/Logo-v_3.png","contentUrl":"https:\/\/decolightingitaly.com\/wp-content\/uploads\/2024\/10\/Logo-v_3.png","width":852,"height":684,"caption":"Decolightingitaly"},"image":{"@id":"https:\/\/decolightingitaly.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Decolighting-Italy\/61570211287982\/"]}]}},"_links":{"self":[{"href":"https:\/\/decolightingitaly.com\/de\/wp-json\/wp\/v2\/product_cat\/138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decolightingitaly.com\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/decolightingitaly.com\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/decolightingitaly.com\/de\/wp-json\/wp\/v2\/product_cat\/105"}],"wp:post_type":[{"href":"https:\/\/decolightingitaly.com\/de\/wp-json\/wp\/v2\/product?product_cat=138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}